{"id":9387,"date":"2021-03-25T10:31:17","date_gmt":"2021-03-25T10:31:17","guid":{"rendered":"https:\/\/expleoacademy.com\/de-de\/glossar\/explanation\/testability-quality-attribute\/"},"modified":"2021-03-25T10:31:17","modified_gmt":"2021-03-25T10:31:17","slug":"testability-quality-attribute","status":"publish","type":"explanation","link":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/","title":{"rendered":"Testability Quality Attribute"},"content":{"rendered":"<h3>Was bedeutet Testability Quality Attribute?<\/h3>\n<p>Das\u00a0<a href=\"https:\/\/expleoacademy.com\/dach\/ueber-uns\/unsere-partner\/isaqb-das-international-software-architecture-qualification-board\/\">International Software Architecture Qualification Board<\/a>\u00a0 (<a href=\"https:\/\/expleoacademy.com\/dach\/ueber-uns\/unsere-partner\/isaqb-das-international-software-architecture-qualification-board\/\">ISAQB<\/a>) definiert den Begriff <em>&#8220;Testability Quality Attribute&#8221;<\/em> wie folgt:<\/p>\n<blockquote><p>Unter Testability Quality Attribute versteht man <span style=\"font-size: 1rem\">&#8220;<\/p>\n<div>\n<p>Degree of effectiveness and efficiency with which test criteria can be established for a system, product or component and tests can be performed to determine whether those criteria have been met<br \/>Is a sub-characteristic of: <a href=\"\/de-de\/#term-maintainability-quality-attribute\">maintainability<\/a><br \/>Refer to <a href=\"http:\/\/iso25000.com\/index.php\/en\/iso-25000-standards\/iso-25010\">ISO 25010<\/a> website<br \/>Category: Quality, ISO 25010<\/p>\n<\/div>\n<p>&#8220;<\/span><\/p><\/blockquote>\n<p>Wenn Sie \u00e4hnliche Fachbegriffe wie <strong>Testability Quality Attribute<\/strong> nachschlagen m\u00fcssen, schauen Sie doch einfach in unserm umfangreichen <a href=\"https:\/\/expleoacademy.com\/de-de\/glossar\/\">Glossar<\/a> nach. Oder durchsuchen Sie unser W\u00f6rterbuch:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Testability Quality Attribute &#8211; In unserem Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"footnotes":""},"class_list":["post-9387","explanation","type-explanation","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Testability Quality Attribute - Glossar, Fachbegriff<\/title>\n<meta name=\"description\" content=\"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Testability Quality Attribute - W\u00f6rterbuch, Glossar, Lexikon - Expleo Academy\" \/>\n<meta property=\"og:description\" content=\"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/\" \/>\n<meta property=\"og:site_name\" content=\"Expleo Academy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Testability Quality Attribute - W\u00f6rterbuch, Glossar, Lexikon - Expleo Academy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/testability-quality-attribute\\\/\",\"url\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/testability-quality-attribute\\\/\",\"name\":\"Testability Quality Attribute - Glossar, Fachbegriff\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#website\"},\"datePublished\":\"2021-03-25T10:31:17+00:00\",\"description\":\"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/testability-quality-attribute\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/testability-quality-attribute\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/testability-quality-attribute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Glossar \\\/ W\u00f6rterbuch \\\/ Lexikon\",\"item\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/glossar\\\/erklaerung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Testability Quality Attribute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#website\",\"url\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/\",\"name\":\"Expleo Academy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#organization\",\"name\":\"Expleo Academy\",\"url\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/02\\\/logo.svg\",\"width\":858,\"height\":396,\"caption\":\"Expleo Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/expleoacademy.com\\\/de-de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Testability Quality Attribute - Glossar, Fachbegriff","description":"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/","og_locale":"de_DE","og_type":"article","og_title":"Testability Quality Attribute - W\u00f6rterbuch, Glossar, Lexikon - Expleo Academy","og_description":"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute","og_url":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/","og_site_name":"Expleo Academy","twitter_card":"summary_large_image","twitter_title":"Testability Quality Attribute - W\u00f6rterbuch, Glossar, Lexikon - Expleo Academy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","FAQPage"],"@id":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/","url":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/","name":"Testability Quality Attribute - Glossar, Fachbegriff","isPartOf":{"@id":"https:\/\/expleoacademy.com\/de-de\/#website"},"datePublished":"2021-03-25T10:31:17+00:00","description":"Testability Quality Attribute - In unserem ISAQB Glossar finden Sie eine Erkl\u00e4rung des Fachbegriffs Testability Quality Attribute","breadcrumb":{"@id":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/testability-quality-attribute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/expleoacademy.com\/de-de\/"},{"@type":"ListItem","position":2,"name":"Glossar \/ W\u00f6rterbuch \/ Lexikon","item":"https:\/\/expleoacademy.com\/de-de\/glossar\/erklaerung\/"},{"@type":"ListItem","position":3,"name":"Testability Quality Attribute"}]},{"@type":"WebSite","@id":"https:\/\/expleoacademy.com\/de-de\/#website","url":"https:\/\/expleoacademy.com\/de-de\/","name":"Expleo Academy","description":"","publisher":{"@id":"https:\/\/expleoacademy.com\/de-de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleoacademy.com\/de-de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleoacademy.com\/de-de\/#organization","name":"Expleo Academy","url":"https:\/\/expleoacademy.com\/de-de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleoacademy.com\/de-de\/#\/schema\/logo\/image\/","url":"https:\/\/expleoacademy.com\/de-de\/wp-content\/uploads\/sites\/5\/2025\/02\/logo.svg","contentUrl":"https:\/\/expleoacademy.com\/de-de\/wp-content\/uploads\/sites\/5\/2025\/02\/logo.svg","width":858,"height":396,"caption":"Expleo Academy"},"image":{"@id":"https:\/\/expleoacademy.com\/de-de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/expleoacademy.com\/de-de\/wp-json\/wp\/v2\/explanation\/9387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleoacademy.com\/de-de\/wp-json\/wp\/v2\/explanation"}],"about":[{"href":"https:\/\/expleoacademy.com\/de-de\/wp-json\/wp\/v2\/types\/explanation"}],"version-history":[{"count":0,"href":"https:\/\/expleoacademy.com\/de-de\/wp-json\/wp\/v2\/explanation\/9387\/revisions"}],"wp:attachment":[{"href":"https:\/\/expleoacademy.com\/de-de\/wp-json\/wp\/v2\/media?parent=9387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}